{"id":9395,"date":"2021-10-26T16:03:36","date_gmt":"2021-10-26T21:03:36","guid":{"rendered":"https:\/\/amc.gov.co\/amc\/?p=7330"},"modified":"2022-11-02T11:56:18","modified_gmt":"2022-11-02T16:56:18","slug":"alcaldia-de-los-patios-le-apuesta-a-integracion-social-binacional","status":"publish","type":"post","link":"https:\/\/amc.gov.co\/amc\/alcaldia-de-los-patios-le-apuesta-a-integracion-social-binacional\/","title":{"rendered":"ALCALD\u00cdA DE LOS PATIOS LE APUESTA A INTEGRACI\u00d3N SOCIAL BINACIONAL"},"content":{"rendered":"<div class=\"vce-row-container\"><div class=\"vce-row vce-row--col-gap-30 vce-row-equal-height vce-row-content--top\" id=\"el-43da31ab\" data-vce-do-apply=\"all el-43da31ab\" data-vce-full-width=\"true\" data-vce-stretch-content=\"true\"><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-749a9e06\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-749a9e06\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-749a9e06\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-6128d780\" data-vce-do-apply=\"all el-6128d780\"><h1>ALCALD\u00cdA DE LOS PATIOS LE APUESTA A INTEGRACI\u00d3N SOCIAL BINACIONAL<\/h1><br><ul><br><li>La Alcald\u00eda de Los Patios en cabeza de nuestro alcalde metropolitano Jose Miguel Bonilla Castiblanco, recibi\u00f3 el Premio Nacional de Alta Gerencia, en la categor\u00eda Gesti\u00f3n Integral de la Migraci\u00f3n.<\/li><br><li>Se otorg\u00f3 un diplomado del 100% en la Fundaci\u00f3n Universitaria Compensar, para un cupo m\u00e1ximo de 10 personas y una asistencia t\u00e9cnica para expandir el impacto de la experiencia postulada.<\/li><br><\/ul><br><p>Este reconocimiento fue otorgado en las instalaciones de la Casa de Nari\u00f1o, por el Departamento Administrativo de la Funci\u00f3n P\u00fablica debido a la iniciativa que lidera actualmente la administraci\u00f3n municipal <em>\u201cFormaci\u00f3n art\u00edstica y cultural para la integraci\u00f3n social binacional\u201d.<\/em><\/p><br><p>El Premio Nacional de Alta Gerencia (PNAG), es el incentivo por excelencia al buen desempe\u00f1o institucional de las entidades p\u00fablicas colombianas. Tiene como prop\u00f3sito el reconocimiento de experiencias exitosas que promuevan, entre otros aspectos, la legalidad, el emprendimiento y la equidad, a trav\u00e9s de la innovaci\u00f3n p\u00fablica.<\/p><br><p>\u201cEste galard\u00f3n se otorg\u00f3 este a\u00f1o a la gesti\u00f3n de distintas pol\u00edticas p\u00fablicas en medio de la pandemia. Aqu\u00ed se demuestra que la administraci\u00f3n p\u00fablica atendi\u00f3 la pandemia, la sigue atendiendo, pero sigue tambi\u00e9n avanzando en m\u00faltiples frentes\u201d, expres\u00f3 el presidente de la Rep\u00fablica, Iv\u00e1n Duque.<\/p><br><p>El programa con el fue galardonada la Alcald\u00eda de Los Patios tiene como objetivo integrar a migrantes venezolanos a los servicios de la secretaria de cultura, a trav\u00e9s de la localizaci\u00f3n de l\u00edderes de esa comunidad se logro identificar y hacer part\u00edcipes a 1.000 personas, quienes son beneficiadas con la estrategia que busca favorecer al entorno colectivo y personal del municipio.<\/p><br><p>Asimismo, como parte del reconocimiento la Alcald\u00eda de Los Patios se hace merecedora de un Diplomado del 100% en la Fundaci\u00f3n Universitaria Compensar, para un cupo m\u00e1ximo de 10 personas y una asistencia t\u00e9cnica para expandir el impacto de la experiencia postulada.<\/p><br><br class=\"wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><figure class=\"wp-block-gallery columns-1 is-cropped\"><br><ul class=\"blocks-gallery-grid\"><br><li class=\"blocks-gallery-item\"><br><figure><img decoding=\"async\" class=\"wp-image-7338\" src=\"https:\/\/amc.gov.co\/amc\/wp-content\/uploads\/2021\/10\/entrega_reconocimiento-2.jpeg\" alt=\"\" data-id=\"7338\" data-full-url=\"https:\/\/amc.gov.co\/amc\/wp-content\/uploads\/2021\/10\/entrega_reconocimiento-2.jpeg\" data-link=\"https:\/\/amc.gov.co\/amc\/index.php\/2021\/10\/26\/alcaldia-de-los-patios-le-apuesta-a-integracion-social-binacional\/entrega_reconocimiento-2-2\/\"><\/figure><br><\/li><br><\/ul><br><\/figure><br><br><br><br><p>&nbsp;<\/p><br><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vce-row-container\"><div class=\"vce-row vce-element--has-background vce-row--col-gap-30 vce-row-content--top\" data-vce-full-width=\"true\" data-vce-stretch-content=\"true\" id=\"el-5fbd7bab\" data-vce-do-apply=\"all el-5fbd7bab\"><div class=\"vce-content-background-container\"><div class=\"vce-asset-background-simple-container vce-visible-all-only vce-asset-background-simple--style-cover vce-asset-background-simple--position-center-top\"><div class=\"vce-asset-background-simple\">\r\n              <div class=\"vce-asset-background-simple-item vcv-lozad\" data-background-image=\"https:\/\/www.aunap.gov.co\/wp-content\/uploads\/2021\/08\/fondo-contadores.png\"><\/div>\r\n              <noscript>\r\n                <div class=\"vce-asset-background-simple-item\" style=\"background-image: url(https:\/\/www.aunap.gov.co\/wp-content\/uploads\/2021\/08\/fondo-contadores.png)\"><\/div>\r\n              <\/noscript>\r\n            <\/div><\/div><\/div><div class=\"vce-row-content\" data-vce-element-content=\"true\"><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-first vce-col--lg-first vce-col--xl-first\" id=\"el-e467aab0\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-e467aab0\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-e467aab0\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-bf68086e\" data-vce-do-apply=\"all el-bf68086e\"><ul class=\"section-imprimir\"><br> \t<li class=\"share-print\" role=\"presentation\"><a title=\"Imprimir\" href=\"javascript:window.print(); void 0;\"><span class=\"fa fa-print fa-2x\" aria-hidden=\"true\"><\/span><span class=\"hidden\">Imprimir<\/span><\/a><\/li><br><\/ul><\/div><\/div><\/div><\/div><\/div><div class=\"vce-col vce-col--md-auto vce-col--xs-1 vce-col--xs-last vce-col--xs-first vce-col--sm-last vce-col--sm-first vce-col--md-last vce-col--lg-last vce-col--xl-last\" id=\"el-f6288bbe\"><div class=\"vce-col-inner\" data-vce-do-apply=\"border margin background  el-f6288bbe\"><div class=\"vce-col-content\" data-vce-element-content=\"true\" data-vce-do-apply=\"padding el-f6288bbe\"><div class=\"vce-text-block\"><div class=\"vce-text-block-wrapper vce\" id=\"el-ac164059\" data-vce-do-apply=\"all el-ac164059\"><div class=\"section-count\">N\u00famero de visitas a esta p\u00e1gina 0<br>Fecha de publicaci\u00f3n 26 octubre, 2021<br>\u00daltima modificaci\u00f3n 2 noviembre, 2022<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>ALCALD\u00cdA DE LOS PATIOS LE APUESTA A INTEGRACI\u00d3N SOCIAL BINACIONALLa Alcald\u00eda de Los Patios en cabeza de nuestro alcalde metropolitano Jose Miguel Bonilla Castiblanco, recibi\u00f3 el Premio Nacional de Alta Gerencia, en la categor\u00eda Gesti\u00f3n Integral de la Migraci\u00f3n.Se otorg\u00f3 un diplomado del 100% en la Fundaci\u00f3n Universitaria Compensar, para un cupo m\u00e1ximo de 10&hellip; <a class=\"more-link\" href=\"https:\/\/amc.gov.co\/amc\/alcaldia-de-los-patios-le-apuesta-a-integracion-social-binacional\/\">Seguir leyendo <span class=\"screen-reader-text\">ALCALD\u00cdA DE LOS PATIOS LE APUESTA A INTEGRACI\u00d3N SOCIAL BINACIONAL<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":9398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_joinchat":[]},"categories":[12],"tags":[],"_links":{"self":[{"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/posts\/9395"}],"collection":[{"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/comments?post=9395"}],"version-history":[{"count":1,"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/posts\/9395\/revisions"}],"predecessor-version":[{"id":11898,"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/posts\/9395\/revisions\/11898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/media\/9398"}],"wp:attachment":[{"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/media?parent=9395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/categories?post=9395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amc.gov.co\/amc\/wp-json\/wp\/v2\/tags?post=9395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}